{"id":1826,"date":"2018-10-23T19:00:13","date_gmt":"2018-10-23T17:00:13","guid":{"rendered":"https:\/\/2018.granada.wordcamp.org\/?p=1826"},"modified":"2018-10-29T15:58:26","modified_gmt":"2018-10-29T14:58:26","slug":"empieza-a-usar-git-para-todo-de-la-mano-de-jj-merelo","status":"publish","type":"post","link":"https:\/\/granada.wordcamp.org\/2018\/desarrollo\/empieza-a-usar-git-para-todo-de-la-mano-de-jj-merelo\/","title":{"rendered":"Empieza a usar git para todo de la mano de JJ Merelo"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/2018.granada.wordcamp.org\/files\/2018\/10\/jj-merelo-1.png\" alt=\"JJ Merelo \u00a1Git! (\u00a1Push!) \u00bfPara qu\u00e9 sirve? \u00a1Absolutamente para todo!\" class=\"wp-image-1807\" srcset=\"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jj-merelo-1.png 1200w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jj-merelo-1-300x158.png 300w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jj-merelo-1-768x403.png 768w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jj-merelo-1-1024x538.png 1024w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jj-merelo-1-500x263.png 500w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Profesor titular de la Universidad de Granada, <a href=\"https:\/\/2018.granada.wordcamp.org\/speaker\/jj-merelo\/\">JJ Merelo<\/a> utiliza <a href=\"https:\/\/2018.granada.wordcamp.org\/session\/git-push-para-que-sirve-absolutamente-para-todo\/\">Git para absolutamente todo<\/a>. \u00a1S\u00ed, c\u00f3mo oyes! No s\u00f3lo para desarrollo de software, JJ ha escrito libros e incluso gestiona con GIT la lista de la compra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precisamente su charla girar\u00e1 entorno a c\u00f3mo se puede generar un h\u00e1bito para usar la tecnolog\u00eda GIT en t\u00fa d\u00eda a d\u00eda y qu\u00e9 ventajas puede ofrecerte. Por lo tanto, si quieres saber m\u00e1s sobre GIT, no puedes dejar pasar la oportunidad de asistir a su charla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes encontrar a JJ Merelo en su <a href=\"https:\/\/twitter.com\/jjmerelo?lang=es\">twitter<\/a>\u00a0y <a href=\"https:\/\/github.com\/JJ\">github<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profesor titular de la Universidad de Granada, JJ Merelo utiliza Git para absolutamente todo. \u00a1S\u00ed, c\u00f3mo oyes! No s\u00f3lo para desarrollo de software, JJ ha escrito libros e incluso gestiona con GIT la lista de la compra. Precisamente su charla girar\u00e1 entorno a c\u00f3mo se puede generar un h\u00e1bito para usar la tecnolog\u00eda GIT en [&hellip;]<\/p>\n","protected":false},"author":14795378,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[209903],"tags":[],"class_list":["post-1826","post","type-post","status-publish","format-standard","hentry","category-desarrollo"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLwK-ts","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/14795378"}],"replies":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1826"}],"version-history":[{"count":3,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1826\/revisions"}],"predecessor-version":[{"id":1927,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1826\/revisions\/1927"}],"wp:attachment":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}