{"id":1863,"date":"2018-11-09T17:00:04","date_gmt":"2018-11-09T16:00:04","guid":{"rendered":"https:\/\/2018.granada.wordcamp.org\/?p=1863"},"modified":"2018-10-23T23:34:13","modified_gmt":"2018-10-23T21:34:13","slug":"david-navia-le-da-carino-a-la-libreria-multimedia","status":"publish","type":"post","link":"https:\/\/granada.wordcamp.org\/2018\/general\/david-navia-le-da-carino-a-la-libreria-multimedia\/","title":{"rendered":"David Navia le da cari\u00f1o a la librer\u00eda multimedia"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/2018.granada.wordcamp.org\/files\/2018\/10\/david-navia.png\" alt=\"David Navia. D\u00e1ndole cari\u00f1o a la librer\u00eda multimedia.\" class=\"wp-image-1789\" srcset=\"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/david-navia.png 1200w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/david-navia-300x158.png 300w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/david-navia-768x403.png 768w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/david-navia-1024x538.png 1024w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/david-navia-500x263.png 500w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Trabajas con WordPress a diario y seguro que utilizas su librer\u00eda multimedia d\u00eda s\u00ed, y d\u00eda tambi\u00e9n \u00a1Y es que es una herramienta esencial! Sin embargo, es probable que tambi\u00e9n alguna vez (o m\u00e1s bien muchas) hayas experimentado dificultades para utilizarla y gestionarla correctamente, o te hayas encontrado con ingentes cantidades de archivos dif\u00edcilmente manejables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta charla, David Navia te explicar\u00e1 c\u00f3mo darle un poquito de amor a esta importante herramienta cont\u00e1ndote cu\u00e1les son las mejores pr\u00e1cticas para que aprendas a usarla y gestionarla sin problemas. Adem\u00e1s, te explicar\u00e1 algunos casos de uso y tambi\u00e9n qu\u00e9 plugins hay disponibles en repositorio para ampliar y mejorar sus funcionalidades.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conociendo a David Navia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">David se describe como \u00abhumano y geek\u00bb. Un viajero empedernido y desarrollador WordPress desde 2008. Amante del UX y, actualmente, inmerso en una relaci\u00f3n (abierta) con las interfaces de administraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Navia participa activamente en la comunidad WordPress Espa\u00f1a, ya sea evangelizando sobre buenas pr\u00e1cticas, traduciendo plugins, o como ponente en Meetups y WordCamps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si quieres echarle un ojo a su trabajo puedes visitar <a href=\"https:\/\/davidnaviaweb.com\/\" target=\"_blank\">davidnaviaweb.com<\/a>.\u00a0 <br \/>donde, como \u00e9l mismo afirma; \u00abjuega\u00bb a \u2018elegir su propia propia aventura\u2018\u00a0 Tambi\u00e9n le puedes seguir en redes sociales como <a href=\"https:\/\/twitter.com\/davidnaviaweb?lang=es\" target=\"_blank\">@davidnaviaweb<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajas con WordPress a diario y seguro que utilizas su librer\u00eda multimedia d\u00eda s\u00ed, y d\u00eda tambi\u00e9n \u00a1Y es que es una herramienta esencial! Sin embargo, es probable que tambi\u00e9n alguna vez (o m\u00e1s bien muchas) hayas experimentado dificultades para utilizarla y gestionarla correctamente, o te hayas encontrado con ingentes cantidades de archivos dif\u00edcilmente manejables. [&hellip;]<\/p>\n","protected":false},"author":15138731,"featured_media":1789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[106],"tags":[],"class_list":["post-1863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLwK-u3","jetpack_featured_media_url":"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/david-navia.png","_links":{"self":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15138731"}],"replies":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1863"}],"version-history":[{"count":4,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1863\/revisions"}],"predecessor-version":[{"id":1995,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1863\/revisions\/1995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/1789"}],"wp:attachment":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}