{"id":1870,"date":"2018-10-28T17:00:13","date_gmt":"2018-10-28T16:00:13","guid":{"rendered":"https:\/\/2018.granada.wordcamp.org\/?p=1870"},"modified":"2018-10-27T06:43:37","modified_gmt":"2018-10-27T04:43:37","slug":"wordque-wordpress-desde-cero-con-jose-arcos-preparados-listos-descarga-instala-ya","status":"publish","type":"post","link":"https:\/\/granada.wordcamp.org\/2018\/wordpress-desde-cero\/wordque-wordpress-desde-cero-con-jose-arcos-preparados-listos-descarga-instala-ya\/","title":{"rendered":"\u00bfWordQu\u00e9? \u00a1WordPress! Desde cero con Jos\u00e9 Arcos. Preparados, listos, descarga, instala \u00a1ya!"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1199\" height=\"630\" src=\"https:\/\/2018.granada.wordcamp.org\/files\/2018\/10\/jose-arcos.png\" alt=\"Jos\u00e9 Arcos. Primeros pasos con WordPress.\" class=\"wp-image-1812\" srcset=\"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jose-arcos.png 1199w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jose-arcos-300x158.png 300w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jose-arcos-768x404.png 768w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jose-arcos-1024x538.png 1024w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jose-arcos-500x263.png 500w\" sizes=\"auto, (max-width: 1199px) 100vw, 1199px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 ser\u00e1 tu gu\u00eda en este <strong>viaje inici\u00e1tico en el universo WordPress<\/strong>. Te acompa\u00f1ar\u00e1 e instruir\u00e1 en los primeros pasos que necesitar\u00e1s dar para empezar a publicar en tu nuevo sitio web: requisitos de WordPress, descargar e instalar WordPress, conectarte al panel de administraci\u00f3n de WordPress.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empezar de manera firme y segura tu nueva relaci\u00f3n con WordPress gracias a Jose te dar\u00e1 la confianza necesaria en el uso de este gestor de contenidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te pierdas su taler\u00a0<strong><a href=\"https:\/\/2018.granada.wordcamp.org\/session\/primeros-pasos-con-wordpress\/\">Primeros pasos con WordPress<\/a><\/strong> para empezar con buen pie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Acerca de Jos\u00e9 Arcos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jos\u00e9 Arcos<\/strong>\u00a0(<a href=\"https:\/\/twitter.com\/josearcos_\" target=\"_blank\" rel=\"noopener\">@josearcos_<\/a>) es desarrollador de WordPress, formador, organizador de la\u00a0<a href=\"https:\/\/betabeers.com\/community\/betabeers-huelva-169\/\" target=\"_blank\" rel=\"noopener\">Betabeers Huelva<\/a>, colabora como moderador en foros de soporte de WordPress en espa\u00f1ol y es t\u00e9cnico de soporte para el plugin multiling\u00fce WPML. <em>Geek<\/em>\u00a0de vocaci\u00f3n, ya de peque\u00f1ito destripaba cualquier aparato que tuviera un circuito impreso en su interior, cruza su trayectoria profesional con WorPress hay\u00e1 por el 2012, momento en el que inicia su andadura profesional en el desarrollo web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes conocer m\u00e1s de Jos\u00e9 Arcos en su <a href=\"https:\/\/www.linkedin.com\/in\/josearcoscampos\/\" target=\"_blank\">perfil de LinkedIn<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 ser\u00e1 tu gu\u00eda en este viaje inici\u00e1tico en el universo WordPress. Te acompa\u00f1ar\u00e1 e instruir\u00e1 en los primeros pasos que necesitar\u00e1s dar para empezar a publicar en tu nuevo sitio web: requisitos de WordPress, descargar e instalar WordPress, conectarte al panel de administraci\u00f3n de WordPress. Empezar de manera firme y segura tu nueva relaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":7771482,"featured_media":1812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1250081],"tags":[],"class_list":["post-1870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress-desde-cero"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLwK-ua","jetpack_featured_media_url":"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/jose-arcos.png","_links":{"self":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/7771482"}],"replies":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1870"}],"version-history":[{"count":12,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1870\/revisions"}],"predecessor-version":[{"id":2206,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1870\/revisions\/2206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/1812"}],"wp:attachment":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}