{"id":1900,"date":"2018-11-11T12:00:33","date_gmt":"2018-11-11T11:00:33","guid":{"rendered":"https:\/\/2018.granada.wordcamp.org\/?p=1900"},"modified":"2018-11-03T11:13:10","modified_gmt":"2018-11-03T10:13:10","slug":"extender-la-funcionalidad-de-wordpress","status":"publish","type":"post","link":"https:\/\/granada.wordcamp.org\/2018\/wordpress-desde-cero\/extender-la-funcionalidad-de-wordpress\/","title":{"rendered":"Extender la funcionalidad de WordPress"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/2018.granada.wordcamp.org\/files\/2018\/10\/fernando-puente.png\" alt=\"Fernando Puente. Extender la funcionalidad de WordPress.\" class=\"wp-image-1811\" srcset=\"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/fernando-puente.png 1200w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/fernando-puente-300x158.png 300w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/fernando-puente-768x403.png 768w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/fernando-puente-1024x538.png 1024w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/fernando-puente-500x263.png 500w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">WordPress va m\u00e1s all\u00e1 de la funcionalidad que ofrece en la instalaci\u00f3n inicial \u00bfnecesitas mostrar un portfolio? \u00bfgestionar un comercio electr\u00f3nico? Vitamina tu instalaci\u00f3n de WordPress con <strong>plugins para extender su funcionalidad<\/strong>\u00a0y adaptarlo a tu proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fernando Puente<\/strong> te explicar\u00e1 de manera magistral <strong>qu\u00e9 son y c\u00f3mo se usan los plugins<\/strong>\u00a0en su taller\u00a0<strong><a href=\"https:\/\/2018.granada.wordcamp.org\/session\/extender-la-funcionalidad-de-wordpress\/\">Extender la funcionalidad de WordPress<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Acerca de Fernando Puente<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fernando Puente<\/strong> es inform\u00e1tico de vocaci\u00f3n y de profesi\u00f3n, formador ocasional de WordPress para periodistas y beginner de comer y beber.\u00a0Desde 1996 trabajando en TI, y los \u00faltimos 12 en medios de comunicaci\u00f3n y comercio electr\u00f3nico con WordPress. Trabaja con WordPress desde 2007.\u00a0Esta especializado en performance para grandes medios y comercio online. Todo un referente en nuestra comunidad WordPress.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WordPress va m\u00e1s all\u00e1 de la funcionalidad que ofrece en la instalaci\u00f3n inicial \u00bfnecesitas mostrar un portfolio? \u00bfgestionar un comercio electr\u00f3nico? Vitamina tu instalaci\u00f3n de WordPress con plugins para extender su funcionalidad\u00a0y adaptarlo a tu proyecto. Fernando Puente te explicar\u00e1 de manera magistral qu\u00e9 son y c\u00f3mo se usan los plugins\u00a0en su taller\u00a0Extender la funcionalidad [&hellip;]<\/p>\n","protected":false},"author":7771482,"featured_media":1811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1250081],"tags":[],"class_list":["post-1900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress-desde-cero"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLwK-uE","jetpack_featured_media_url":"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/10\/fernando-puente.png","_links":{"self":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/7771482"}],"replies":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1900"}],"version-history":[{"count":6,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1900\/revisions"}],"predecessor-version":[{"id":2211,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1900\/revisions\/2211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/1811"}],"wp:attachment":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}