{"id":2367,"date":"2018-11-09T18:20:59","date_gmt":"2018-11-09T17:20:59","guid":{"rendered":"https:\/\/2018.granada.wordcamp.org\/?p=2367"},"modified":"2018-11-14T19:49:56","modified_gmt":"2018-11-14T18:49:56","slug":"365-neptuno-local-afterparty","status":"publish","type":"post","link":"https:\/\/granada.wordcamp.org\/2018\/uncategorized\/365-neptuno-local-afterparty\/","title":{"rendered":"365 Neptuno. Contamos con el mejor local para la Afterparty"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/2018.granada.wordcamp.org\/files\/2018\/11\/365Neptuno.jpg\" alt=\"365Neptuno\" class=\"wp-image-2369\" srcset=\"https:\/\/granada.wordcamp.org\/2018\/files\/2018\/11\/365Neptuno.jpg 960w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/11\/365Neptuno-300x200.jpg 300w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/11\/365Neptuno-768x512.jpg 768w, https:\/\/granada.wordcamp.org\/2018\/files\/2018\/11\/365Neptuno-450x300.jpg 450w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><figcaption>365 Neptuno, Tienes que venir<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando nos planteamos seleccionar un local para la afterparty de esta nuestra primera WordCamp, no dudamos en contactar con nuestros amigos de <strong>365 Neptuno<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese momento, tanto <strong>Isra <\/strong>(Co-Fundador del local), como <strong>Marien <\/strong>(Responsable de Marketing, eventos y RR.PP) se volcaron con nosotros y comenzaron a ofrecernos facilidades e ideas para que la noche sea <strong>lo m\u00e1s divertida y confortable posible<\/strong>.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a ellos, vamos a disponer de una <strong>zona reservada<\/strong> para nosotros, donde podremos charlar tranquilamente y continuar con el networking, si es que a\u00fan te quedan ganas. Pero tambi\u00e9n, si lo deseas, podr\u00e1s unirte a la <strong>pista principal<\/strong> o salir a su <strong>terraza chill-out<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos a la vez abrumados por su amabilidad e impacientes porque nos consta que son los mejores de Granada organizando eventos. Adem\u00e1s, sabemos que nos tienen preparadas muchas sorpresas, as\u00ed que nada de procrastinar con la fiesta&#8230; \u00a1Tienes que venir!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">C\u00f3mo llegar<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Muy cerquita del local se encuentra la parada de metro <strong>Recogidas<\/strong>, adem\u00e1s hay varias l\u00edneas de autob\u00fas que pueden dejarte al lado. Pero si quieres ir caminando desde el Palacio de Congresos, est\u00e1 a menos de 20 minutos. Os dejamos el trayecto m\u00e1s corto seg\u00fan google maps:<\/p>\n\n\n\n<div class=\"googlemaps\">\n\t\t\t\t<iframe loading=\"lazy\" width=\"800\" height=\"600\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"  src=\"https:\/\/www.google.com\/maps\/embed?pb=%211m28%211m12%211m3%211d6358.847746807983%212d-3.6077282736865044%213d37.16639646949893%212m3%211f0%212f0%213f0%213m2%211i1024%212i768%214f13.1%214m13%213e2%214m5%211s0xd71fca305aa656b%3A0xde24e4346346018%212sPalacio%20de%20Congresos%20de%20Granada%2C%20Paseo%20del%20Viol%C3%B3n%2C%20Granada%213m2%211d37.165396799999996%212d-3.5986824%214m5%211s0xd71fc90907870d9%3A0xf7fba751cf22cb0b%212sCalle%20Neptuno%2C%20365%2C%2018004%20Granada%213m2%211d37.168292699999995%212d-3.6083746999999997%215e0%213m2%211ses%212ses%214v1541455367416\"><\/iframe>\n\t\t\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Como suponemos que antes querr\u00e1s cenar, el propio local 365 dispone de restaurante italiano y pizzer\u00eda. Tambi\u00e9n, tanto en en la zona de la Calle Alhamar y San Ant\u00f3n, podr\u00e1s tapear. Pero adem\u00e1s, justo al lado del local del After Party hay un Foster&#8217;s Hollywood y cerca est\u00e1 el m\u00edtico Il gondoliere (por la zona de Plaza de Gracia). Vamos, que con hambre no te quedar\u00e1s para la fiesta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando nos planteamos seleccionar un local para la afterparty de esta nuestra primera WordCamp, no dudamos en contactar con nuestros amigos de 365 Neptuno. En ese momento, tanto Isra (Co-Fundador del local), como Marien (Responsable de Marketing, eventos y RR.PP) se volcaron con nosotros y comenzaron a ofrecernos facilidades e ideas para que la noche [&hellip;]<\/p>\n","protected":false},"author":15138731,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,9745],"tags":[],"class_list":["post-2367","post","type-post","status-publish","format-standard","hentry","category-uncategorized","category-patrocinador"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLwK-Cb","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15138731"}],"replies":[{"embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=2367"}],"version-history":[{"count":9,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2367\/revisions"}],"predecessor-version":[{"id":2776,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2367\/revisions\/2776"}],"wp:attachment":[{"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=2367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=2367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granada.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=2367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}